{"id":7,"count":389,"description":"","link":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/","name":"Telef\u00f3nica M\u00f3viles","slug":"telefonica-moviles","taxonomy":"category","parent":8,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Telef\u00f3nica M\u00f3viles archivos - UGT Comunicaciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Telef\u00f3nica M\u00f3viles archivos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/\" \/>\n<meta property=\"og:site_name\" content=\"UGT Comunicaciones\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2021\/07\/cropped-logo_icon_web.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ugtcom\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/category\\\/telefonica-cev\\\/telefonica-moviles\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/category\\\/telefonica-cev\\\/telefonica-moviles\\\/\",\"name\":\"Telef\u00f3nica M\u00f3viles archivos - UGT Comunicaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/category\\\/telefonica-cev\\\/telefonica-moviles\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/category\\\/telefonica-cev\\\/telefonica-moviles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Telef\u00f3nica CEV\",\"item\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/category\\\/telefonica-cev\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Telef\u00f3nica M\u00f3viles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"name\":\"UGT Comunicaciones\",\"description\":\"Sindicato de Telecomunicaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\",\"name\":\"UGT Comunicaciones\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"width\":298,\"height\":81,\"caption\":\"UGT Comunicaciones\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ugt.comunicaciones\\\/\",\"https:\\\/\\\/x.com\\\/ugtcom\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Telef\u00f3nica M\u00f3viles archivos - UGT Comunicaciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/","og_locale":"es_ES","og_type":"article","og_title":"Telef\u00f3nica M\u00f3viles archivos","og_url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/","og_site_name":"UGT Comunicaciones","og_image":[{"width":512,"height":512,"url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2021\/07\/cropped-logo_icon_web.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ugtcom","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/","name":"Telef\u00f3nica M\u00f3viles archivos - UGT Comunicaciones","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/telefonica-moviles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Telef\u00f3nica CEV","item":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/category\/telefonica-cev\/"},{"@type":"ListItem","position":3,"name":"Telef\u00f3nica M\u00f3viles"}]},{"@type":"WebSite","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","name":"UGT Comunicaciones","description":"Sindicato de Telecomunicaciones","publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization","name":"UGT Comunicaciones","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","width":298,"height":81,"caption":"UGT Comunicaciones"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ugt.comunicaciones\/","https:\/\/x.com\/ugtcom"]}]}},"_links":{"self":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories\/7","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories\/8"}],"wp:post_type":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts?categories=7"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}