{"id":1022777,"date":"2022-07-05T08:00:41","date_gmt":"2022-07-05T06:00:41","guid":{"rendered":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?p=1022777"},"modified":"2022-07-04T16:03:51","modified_gmt":"2022-07-04T14:03:51","slug":"ix-reunion-de-la-comision-interempresas-de-igualdad","status":"publish","type":"post","link":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/","title":{"rendered":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span> ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Clasificaci\u00f3n Profesional.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">En el an\u00e1lisis desagregado por sexos de la situaci\u00f3n nos encontramos con un 70% de hombres y un 30% de mujeres Fuera de Convenio y un 66,5% de hombres y un 33,5% de mujeres Dentro de Convenio.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Formaci\u00f3n.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Se ha realizado <strong>formaci\u00f3n dirigida a motivar y potenciar la promoci\u00f3n de mujeres<\/strong> a puestos de responsabilidad (empoderamiento) as\u00ed como formaci\u00f3n en materia de <strong>igualdad y sesgos inconscientes<\/strong>, sobre <strong>prevenci\u00f3n y exclusi\u00f3n de conductas de acoso<\/strong> para plantilla tanto dentro como fuera de convenio y en cuanto a la <strong>formaci\u00f3n en materia de igualdad<\/strong> dirigida a personas que participan en los procesos de selecci\u00f3n, contrataci\u00f3n, promoci\u00f3n y formaci\u00f3n se ha realizado el curso \u201cLidera la Diversidad con \u00e9xito\u201d.<\/p>\n<p style=\"text-align: justify;\">Para <span style=\"color: #ff0000;\"><strong>UGT<\/strong> <\/span><strong>es importante que las personas que gestionan equipos y la direcci\u00f3n de Personas tengan formaci\u00f3n en materia de igualdad, <\/strong>por ello establecimos en el Plan una medida espec\u00edfica, y ya se ha empezado a formar a este colectivo.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n se ha ofrecido formaci\u00f3n en materias espec\u00edficas sobre diversidad como pueden ser \u201cGesti\u00f3n de la diversidad LGTB+ en Telef\u00f3nica\u201d, \u201cElegimos Diversidad\u201d, \u201cDiversidad e Inclusi\u00f3n de las personas con Discapacidad\u201d o \u201cDiscapacidad en el Trabajo: C\u00f3mo abordar la diversidad funcional\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Condiciones de Trabajo.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">En el caso del permiso sobre <strong>Lactancia<\/strong>, un 42% de mujeres y un 58% de hombres han disfrutado del mismo.<\/p>\n<p style=\"text-align: justify;\">En cuanto al <strong>seguimiento de los datos de Teletrabajo y SmartWork<\/strong>, la situaci\u00f3n del disfrute de estos por sexos sobre el total de personas de cada jur\u00eddica es similar a la distribuci\u00f3n real de mujeres y hombres que existe en cada una de las empresas.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Conciliaci\u00f3n y Corresponsabilidad.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Seg\u00fan muestran los datos sobre reducciones de jornada, nos encontramos con que del total de personas que utilizan esta medida, un 24% son hombres y un 76% son mujeres. Esto implica que siguen siendo las mujeres las que, en un porcentaje muy superior a los hombres, renuncian a parte de su salario y su jornada laboral para poder conciliar.<\/p>\n<p style=\"text-align: justify;\"><strong>Para <span style=\"color: #ff0000;\">UGT<\/span> es imprescindible que se apueste por mayores medidas de flexibilidad que permitan conciliar sin tener que renunciar y se faciliten las adaptaciones en lugar de las reducciones de jornada. <\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span> considera positivo que, gracias a la insistencia de este sindicato en la negociaci\u00f3n del Plan de Igualdad, ahora dispongamos de informaci\u00f3n concreta sobre indicadores en cada una de las materias, cuesti\u00f3n que nos permitir\u00e1 medir la evoluci\u00f3n de la situaci\u00f3n en materia de igualdad.<\/p>\n<p style=\"text-align: justify;\">Tanto la informaci\u00f3n sobre medidas e indicadores del resto de materias como la informaci\u00f3n de car\u00e1cter cualitativo del Plan de Igualdad, ser\u00e1 presentada en la pr\u00f3xima reuni\u00f3n prevista para mediados del mes de Julio.<\/p>\n<p style=\"text-align: justify;\">Desde<strong><span style=\"color: #ff0000;\"> UGT<\/span> reclamamos que las reuniones de trabajo se deben realizar, como acordamos con el Plan de Igualdad, en horario que permitan la conciliaci\u00f3n<\/strong>, por lo que insistimos en la necesidad de que se traslade esta cuesti\u00f3n a todos los niveles y se apueste por una correcta desconexi\u00f3n digital.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Seguimiento de los datos de car\u00e1cter Retributivo.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">Seg\u00fan los datos mostrados por la empresa sobre el Registro Retributivo del a\u00f1o 2021, no habr\u00eda brechas retributivas superiores al 25% en retribuci\u00f3n total en ninguna de las tres jur\u00eddicas, ni dentro ni fuera de convenio.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span> considera positivo que nos encontremos en los m\u00e1rgenes que establece la normativa, pero insistimos en que el l\u00edmite del 25% marcado por la misma es muy elevado, por lo que solicitaremos el an\u00e1lisis de cualquier diferencia que requiera justificaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong><u>Diversidad.<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">La empresa informa dentro de esta comisi\u00f3n, pese a entender que no tratamos en la misma Diversidad, si no Igualdad, las diferentes acciones que se est\u00e1n llevando a cabo por la semana del <strong>Orgullo LGTB+,<\/strong> como la presencia en la manifestaci\u00f3n del orgullo y la creaci\u00f3n de una gu\u00eda de acompa\u00f1amiento en la transici\u00f3n de g\u00e9nero.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span> <strong>considera positivo que se apueste por la diversidad <\/strong>y se de visibilidad a todas las acciones que se llevan a cabo.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span> contin\u00faa defendiendo la igualdad entre mujeres y hombres a todos los niveles, analizando los datos y realizando un seguimiento del Plan de Igualdad que nos permita avanzar en este sentido. <strong><span style=\"color: #ff0000;\">UGT<\/span> exige que se apueste por la conciliaci\u00f3n real, fomentando la flexibilidad, la desconexi\u00f3n digital, las adaptaciones de jornada en sustituci\u00f3n de las reducciones, mejorando el teletrabajo y trasladando aquellas cuestiones que nos hac\u00e9is llegar para que se cumplan todos los acuerdos que gracias a esta organizaci\u00f3n se alcanzan.\u00a0 <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad. Clasificaci\u00f3n Profesional. En el an\u00e1lisis desagregado por sexos de la situaci\u00f3n nos encontramos con un 70% de hombres y un 30% de mujeres Fuera de Convenio y un 66,5% de hombres [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":958086,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,25,7,26],"tags":[],"class_list":["post-1022777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-telefonica-cev","category-telefonica","category-telefonica-moviles","category-telefonica-soluciones"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad - UGT Comunicaciones<\/title>\n<meta name=\"description\" content=\"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad\" \/>\n<meta property=\"og:description\" content=\"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/\" \/>\n<meta property=\"og:site_name\" content=\"UGT Comunicaciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ugt.comunicaciones\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T06:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"UGT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:site\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"UGT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/\"},\"author\":{\"name\":\"UGT\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\"},\"headline\":\"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad\",\"datePublished\":\"2022-07-05T06:00:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/\"},\"wordCount\":820,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Firmamos-el-Plan-Igualdad-Telyco-1.png\",\"articleSection\":[\"Telef\u00f3nica CEV\",\"Telef\u00f3nica de Espa\u00f1a\",\"Telef\u00f3nica M\u00f3viles\",\"Telef\u00f3nica Soluciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/\",\"name\":\"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad - UGT Comunicaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Firmamos-el-Plan-Igualdad-Telyco-1.png\",\"datePublished\":\"2022-07-05T06:00:41+00:00\",\"description\":\"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Firmamos-el-Plan-Igualdad-Telyco-1.png\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/Firmamos-el-Plan-Igualdad-Telyco-1.png\",\"width\":1080,\"height\":758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/ix-reunion-de-la-comision-interempresas-de-igualdad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"name\":\"UGT Comunicaciones\",\"description\":\"Sindicato de Telecomunicaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\",\"name\":\"UGT Comunicaciones\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"width\":298,\"height\":81,\"caption\":\"UGT Comunicaciones\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ugt.comunicaciones\\\/\",\"https:\\\/\\\/x.com\\\/ugtcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\",\"name\":\"UGT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"caption\":\"UGT\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad - UGT Comunicaciones","description":"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/","og_locale":"es_ES","og_type":"article","og_title":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad","og_description":"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...","og_url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/","og_site_name":"UGT Comunicaciones","article_publisher":"https:\/\/www.facebook.com\/ugt.comunicaciones\/","article_published_time":"2022-07-05T06:00:41+00:00","og_image":[{"width":1080,"height":758,"url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png","type":"image\/png"}],"author":"UGT","twitter_card":"summary_large_image","twitter_creator":"@ugtcom","twitter_site":"@ugtcom","twitter_misc":{"Escrito por":"UGT","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#article","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/"},"author":{"name":"UGT","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed"},"headline":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad","datePublished":"2022-07-05T06:00:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/"},"wordCount":820,"publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png","articleSection":["Telef\u00f3nica CEV","Telef\u00f3nica de Espa\u00f1a","Telef\u00f3nica M\u00f3viles","Telef\u00f3nica Soluciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/","name":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad - UGT Comunicaciones","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#primaryimage"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png","datePublished":"2022-07-05T06:00:41+00:00","description":"UGT ha asistido a una nueva reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad en la que hemos realizado el Seguimiento del Plan de Igualdad...","breadcrumb":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#primaryimage","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2022\/01\/Firmamos-el-Plan-Igualdad-Telyco-1.png","width":1080,"height":758},{"@type":"BreadcrumbList","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/ix-reunion-de-la-comision-interempresas-de-igualdad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/"},{"@type":"ListItem","position":2,"name":"IX Reuni\u00f3n de la Comisi\u00f3n Interempresas de Igualdad"}]},{"@type":"WebSite","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","name":"UGT Comunicaciones","description":"Sindicato de Telecomunicaciones","publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization","name":"UGT Comunicaciones","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","width":298,"height":81,"caption":"UGT Comunicaciones"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ugt.comunicaciones\/","https:\/\/x.com\/ugtcom"]},{"@type":"Person","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed","name":"UGT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","caption":"UGT"}}]}},"_links":{"self":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/1022777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/comments?post=1022777"}],"version-history":[{"count":0,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/1022777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media\/958086"}],"wp:attachment":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media?parent=1022777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories?post=1022777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/tags?post=1022777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}