{"id":1061992,"date":"2023-02-06T07:00:47","date_gmt":"2023-02-06T05:00:47","guid":{"rendered":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?p=1061992"},"modified":"2023-01-31T12:16:27","modified_gmt":"2023-01-31T10:16:27","slug":"empleo-tech","status":"publish","type":"post","link":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/","title":{"rendered":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada"},"content":{"rendered":"<h4 style=\"text-align: justify;\">A pesar de la insistencia en el relato de patronales y empresas, la realidad laboral del empleo tecnol\u00f3gico en nuestro pa\u00eds no es la que se quiere transmitir. Dos nuevas oleadas de datos vuelven a confirmar las evidencias apuntadas anteriormente por <a href=\"https:\/\/servicioestudiosugt.com\/empleo-tecnologico-en-el-mercado-laboral-espanol\/\" target=\"_blank\" rel=\"noopener\">nuestro Sindicato<\/a>.<\/h4>\n<p style=\"text-align: justify;\">La Encuesta Trimestral de Coste Laboral del <a href=\"https:\/\/www.ine.es\/dyngs\/INEbase\/es\/operacion.htm?c=Estadistica_C&amp;cid=1254736045053&amp;menu=ultiDatos&amp;idp=1254735976596\" target=\"_blank\" rel=\"noopener\">INE<\/a> confirma que el 91,3% de las empresas del Sector TIC no necesita ning\u00fan trabajador nuevo, y por tanto, no tendr\u00eda ni una sola vacante disponible. Y hasta un 6% no cubre sus vacantes porque no quiere abonar el salario que demanda una profesi\u00f3n tan especializada y que exige no solo de alt\u00edsima formaci\u00f3n previa, sino adem\u00e1s de una constante actualizaci\u00f3n de conocimientos. En conclusi\u00f3n, s\u00f3lo un 2,7% admite tener posiciones no cubiertas, para un total de 7.936 vacantes.<\/p>\n<p style=\"text-align: justify;\">Mas all\u00e1 de las sospechas de sobredimensionamiento (resulta dif\u00edcil explicar que menos del 3% de empresas que admiten vacantes insatisfechas acumulen hasta 8.000 de las mismas), lo \u00fanico realmente comprobable es que estamos ante el tercer trimestre consecutivo donde desciende el volumen de vacantes <em>tech<\/em> (un 12% menos en seis meses), confirmando el contagio de los masivos despidos iniciados por las grandes tecnol\u00f3gicas. No obstante, procede poner en contexto la cifra de 8.000 vacantes: comparados con otros sectores clave de nuestra econom\u00eda, representan la mitad de las vacantes existentes en actividades sanitarias, casi tres veces menos que las que existen en el comercio minorista y 5&#8217;5 veces menos de las necesidades declaradas de empleo p\u00fablico (45.424).<\/p>\n<p style=\"text-align: justify;\">Estamos ante las repercusiones de unas pol\u00edticas de contrataci\u00f3n y retenci\u00f3n m\u00e1s centradas en el marketing que en la atenci\u00f3n real a los intereses de las personas trabajadoras del sector TIC. La comparativa internacional es desoladora, como constata el World Talent Ranking 2022 de <a href=\"https:\/\/www.imd.org\/centers\/world-competitiveness-center\/rankings\/world-talent-competitiveness\/\" target=\"_blank\" rel=\"noopener\">IMD<\/a>: de 63 pa\u00edses, Espa\u00f1a se sit\u00faa en el puesto 50 en el \u00edtem <em>\u201cla formaci\u00f3n de los empleados es una alta prioridad en las empresas\u201d<\/em>. En el apartado de <em>\u201catraer y retener talentos como prioridad en las empresas\u201d<\/em>, en el puesto es el 52. Y, finalmente, en <em>\u201cla motivaci\u00f3n de los trabajadores en las empresas es alta\u201d<\/em>, estamos en 48\u00ba lugar.<\/p>\n<p style=\"text-align: justify;\">UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos salpicados de cifras infladas, caracterizados por una publicidad dirigida al exterior, que sus pol\u00edticas laborales internas no suscriben. Es hora de, si verdad se quiere tener el mejor talento, motivarlo en forma de buenos salarios, formaci\u00f3n continua y calidad en el empleo.<\/p>\n<h4 style=\"text-align: right;\"><strong><span style=\"color: #ff0000;\">UGT<\/span> Comunicaciones<\/strong><a href=\"#_ftnref1\" name=\"_ftn1\"><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>A pesar de la insistencia en el relato de patronales y empresas, la realidad laboral del empleo tecnol\u00f3gico en nuestro pa\u00eds no es la que se quiere transmitir. Dos nuevas oleadas de datos vuelven a confirmar las evidencias apuntadas anteriormente por nuestro Sindicato. La Encuesta Trimestral de Coste Laboral del INE confirma que el 91,3% [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1062005,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,12],"tags":[],"class_list":["post-1061992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-comunicaciones","category-regulacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada - UGT Comunicaciones<\/title>\n<meta name=\"description\" content=\"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada\" \/>\n<meta property=\"og:description\" content=\"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/\" \/>\n<meta property=\"og:site_name\" content=\"UGT Comunicaciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ugt.comunicaciones\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T05:00:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"UGT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:site\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"UGT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/\"},\"author\":{\"name\":\"UGT\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\"},\"headline\":\"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada\",\"datePublished\":\"2023-02-06T05:00:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/\"},\"wordCount\":446,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/empleo-tech.jpg\",\"articleSection\":[\"Mercado Comunicaciones\",\"Regulaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/\",\"name\":\"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada - UGT Comunicaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/empleo-tech.jpg\",\"datePublished\":\"2023-02-06T05:00:47+00:00\",\"description\":\"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/empleo-tech.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/empleo-tech.jpg\",\"width\":612,\"height\":408,\"caption\":\"Paperless workplace idea, e-signing, electronic signature, document management. Businessman signs an electronic document on a digital document on a virtual notebook screen using a stylus pen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/empleo-tech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"name\":\"UGT Comunicaciones\",\"description\":\"Sindicato de Telecomunicaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\",\"name\":\"UGT Comunicaciones\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"width\":298,\"height\":81,\"caption\":\"UGT Comunicaciones\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ugt.comunicaciones\\\/\",\"https:\\\/\\\/x.com\\\/ugtcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\",\"name\":\"UGT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"caption\":\"UGT\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada - UGT Comunicaciones","description":"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/","og_locale":"es_ES","og_type":"article","og_title":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada","og_description":"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos","og_url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/","og_site_name":"UGT Comunicaciones","article_publisher":"https:\/\/www.facebook.com\/ugt.comunicaciones\/","article_published_time":"2023-02-06T05:00:47+00:00","og_image":[{"width":612,"height":408,"url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg","type":"image\/jpeg"}],"author":"UGT","twitter_card":"summary_large_image","twitter_creator":"@ugtcom","twitter_site":"@ugtcom","twitter_misc":{"Escrito por":"UGT","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#article","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/"},"author":{"name":"UGT","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed"},"headline":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada","datePublished":"2023-02-06T05:00:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/"},"wordCount":446,"publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg","articleSection":["Mercado Comunicaciones","Regulaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/","name":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada - UGT Comunicaciones","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#primaryimage"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg","datePublished":"2023-02-06T05:00:47+00:00","description":"UGT exige a las compa\u00f1\u00edas tecnol\u00f3gicas un cambio de 180\u00ba en sus pol\u00edticas de recursos humanos. Deben abandonar los discursos","breadcrumb":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#primaryimage","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2023\/02\/empleo-tech.jpg","width":612,"height":408,"caption":"Paperless workplace idea, e-signing, electronic signature, document management. Businessman signs an electronic document on a digital document on a virtual notebook screen using a stylus pen."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/empleo-tech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/"},{"@type":"ListItem","position":2,"name":"La realidad del empleo TECH: ni miles vacantes, ni b\u00fasqueda de talento, ni formaci\u00f3n adecuada"}]},{"@type":"WebSite","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","name":"UGT Comunicaciones","description":"Sindicato de Telecomunicaciones","publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization","name":"UGT Comunicaciones","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","width":298,"height":81,"caption":"UGT Comunicaciones"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ugt.comunicaciones\/","https:\/\/x.com\/ugtcom"]},{"@type":"Person","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed","name":"UGT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","caption":"UGT"}}]}},"_links":{"self":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/1061992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/comments?post=1061992"}],"version-history":[{"count":1,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/1061992\/revisions"}],"predecessor-version":[{"id":1061994,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/1061992\/revisions\/1061994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media\/1062005"}],"wp:attachment":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media?parent=1061992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories?post=1061992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/tags?post=1061992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}