{"id":96194,"date":"2018-02-05T08:00:50","date_gmt":"2018-02-05T06:00:50","guid":{"rendered":"http:\/\/ugtcomunicaciones.es\/wordpress\/?p=96194"},"modified":"2018-01-27T14:38:06","modified_gmt":"2018-01-27T12:38:06","slug":"eeuu-quiere-cambiar-cobre-accesos-inalambricos","status":"publish","type":"post","link":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/","title":{"rendered":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"size-full wp-image-96195 alignleft lazyload\" data-src=\"http:\/\/ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre.jpg\" alt=\"\" width=\"100\" height=\"100\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 100px; --smush-placeholder-aspect-ratio: 100\/100;\" \/>La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama. Si en un principio fue la neutralidad de la red su objetivo, enterrando el concepto<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>, ahora toca el turno del apagado de la red legada de cobre.<\/p>\n<p style=\"text-align: justify;\">Efectivamente, la FCC quiere dar facilidades a los operadores para cerrar sus redes de cobre, pero no sustituy\u00e9ndola por fibra o cable como hasta ahora, sino permitiendo que su sustituci\u00f3n sea posible usando un acceso inal\u00e1mbrico<a href=\"#_ftn2\" name=\"_ftnref2\">[2]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Hasta la fecha, el regulador estadounidense solo permit\u00eda que una l\u00ednea de cobre fuese eliminada cuando era sustituida por un servicio\u00a0<em>al menos\u00a0tan bueno<\/em> como el que proporcionaba la antigua red de cobre<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a>. Para corroborar que dicha sustituci\u00f3n cumpl\u00eda la norma, la FCC creo una \u201cprueba funcional\u201d donde establecer la comparativa<a href=\"#_ftn4\" name=\"_ftnref4\">[4]<\/a>. En la pr\u00e1ctica, esto significaba que si un operador quer\u00eda apagar un acceso de cobre deb\u00eda sustituirlo por una l\u00ednea de fibra o cable HFC. Dicho de otro modo, los operadores deb\u00edan demostrar que el servicio de reemplazo es igual de bueno, y que brinda las mismas capacidades, que el que se est\u00e1 suspendiendo.<\/p>\n<p style=\"text-align: justify;\">La nueva FCC ha relajado la norma, eliminando esta prueba como requisito previo, lo que significa que cualquier operador puede eliminar l\u00edneas de cobre con una simple declaraci\u00f3n de que el \u00e1rea en cuesti\u00f3n disfruta de un acceso alternativo, como podr\u00eda representar la cobertura de un servicio de banda ancha m\u00f3vil. De este modo, los operadores implicados evitar\u00edan instalar fibra o cable para apagar la red legada, reemplazando cobre por acceso inal\u00e1mbricos, lo que representar\u00eda un ahorro de costes muy relevante.<\/p>\n<p style=\"text-align: justify;\">Pero la cuesti\u00f3n es que este cambio normativo encierra un evidente perjuicio para aquellas zonas m\u00e1s vulnerables, normalmente rurales o alejadas de grandes n\u00facleos de poblaci\u00f3n. As\u00ed, estas \u00e1reas no s\u00f3lo se ver\u00edan privadas de acceder a infraestructuras modernas, sino que incluso rebajar\u00edan la calidad de su conexi\u00f3n al pasar a una inestable conexi\u00f3n inal\u00e1mbrica que nadie testear\u00eda antes del apagado de la l\u00ednea de cobre. Es un hecho que, con la anterior norma, donde hab\u00eda cobre tendr\u00eda que haber fibra o cobre, y con esta nueva pauta, ni una cosa ni otra, e incluso una peor.<\/p>\n<p style=\"text-align: justify;\">Este movimiento no ha pasado desapercibido ni para las asociaciones de consumidores\/ONG<a href=\"#_ftn5\" name=\"_ftnref5\">[5]<\/a>, ni para sindicatos<a href=\"#_ftn6\" name=\"_ftnref6\">[6]<\/a> ni para la oposici\u00f3n del Partido Dem\u00f3crata<a href=\"#_ftn7\" name=\"_ftnref7\">[7]<\/a>, que han criticado fuertemente la medida, por insolidaria, discriminatoria y regresiva.<\/p>\n<p style=\"text-align: justify;\">En el otro lado, los operadores, que aplauden el cambio en la ley, gracias a la reducci\u00f3n de costos que implica<a href=\"#_ftn8\" name=\"_ftnref8\">[8]<\/a>.<\/p>\n<p style=\"text-align: justify;\">Para <strong><span style=\"color: #ff0000;\">UGT<\/span> Comunicaciones<\/strong>, la decisi\u00f3n de la administraci\u00f3n Trump es profundamente err\u00f3nea. Si bien es cierto que en nuestro modelo de Sector defendemos el uso de redes inal\u00e1mbricas para llevar internet a zonas desfavorecidas, siempre hemos hablado de zonas sin cobertura de ninguna clase de tecnolog\u00eda. No podemos suscribir ni aceptar que se use un atajo normativo para empeorar la calidad del servicio, que sin duda alguna aumentar\u00e1 la brecha digital e incrementar\u00e1 la fractura social entre aquellos privilegiados con redes de \u00faltima generaci\u00f3n en su hogar y aquellos que nunca podr\u00e1n conectarse a Internet de forma funcional.<\/p>\n<h4 style=\"text-align: right;\"><span style=\"color: #ff0000;\"><strong>UGT<\/strong><\/span><strong> Comunicaciones<\/strong><\/h4>\n<p><span style=\"font-size: xx-small;\"><br \/>\n<a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> <a href=\"http:\/\/ugtcomunicaciones.es\/wordpress\/trump-acaba-la-neutralidad-la-red\/\" target=\"_blank\" rel=\"noopener\">http:\/\/ugtcomunicaciones.es\/wordpress\/trump-acaba-la-neutralidad-la-red\/<\/a><br \/>\n<a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> <a href=\"http:\/\/transition.fcc.gov\/Daily_Releases\/Daily_Business\/2017\/db1026\/DOC-347451A1.pdf\" target=\"_blank\" rel=\"noopener\">http:\/\/transition.fcc.gov\/Daily_Releases\/Daily_Business\/2017\/db1026\/DOC-347451A1.pdf<\/a><br \/>\n<a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> <a href=\"https:\/\/arstechnica.com\/tech-policy\/2017\/11\/fccs-latest-gift-to-telcos-could-leave-americans-with-worse-internet-access\/\" target=\"_blank\" rel=\"noopener\">https:\/\/arstechnica.com\/tech-policy\/2017\/11\/fccs-latest-gift-to-telcos-could-leave-americans-with-worse-internet-access\/<\/a><br \/>\n<a href=\"#_ftnref4\" name=\"_ftn4\">[4]<\/a> <a href=\"https:\/\/apps.fcc.gov\/edocs_public\/attachmatch\/FCC-14-185A1.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/apps.fcc.gov\/edocs_public\/attachmatch\/FCC-14-185A1.pdf<\/a><br \/>\n<a href=\"#_ftnref5\" name=\"_ftn5\">[5]<\/a> <a href=\"https:\/\/www.fiercetelecom.com\/telecom\/fcc-s-copper-retirement-plans-face-repeal-from-non-governmental-organizations\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fiercetelecom.com\/telecom\/fcc-s-copper-retirement-plans-face-repeal-from-non-governmental-organizations<\/a><br \/>\n<a href=\"#_ftnref6\" name=\"_ftn6\">[6]<\/a> <a href=\"https:\/\/ecfsapi.fcc.gov\/file\/11090039324560\/Joint%20Wireline%20Broadband%20Letter%20FINAL.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/ecfsapi.fcc.gov\/file\/11090039324560\/Joint%20Wireline%20Broadband%20Letter%20FINAL.pdf<\/a><br \/>\n<a href=\"#_ftnref7\" name=\"_ftn7\">[7]<\/a> <a href=\"https:\/\/www.hassan.senate.gov\/imo\/media\/doc\/171114.Pai.Wireline.Letter.pdf\" target=\"_blank\" rel=\"noopener\">https:\/\/www.hassan.senate.gov\/imo\/media\/doc\/171114.Pai.Wireline.Letter.pdf<\/a><br \/>\n<a href=\"#_ftnref8\" name=\"_ftn8\">[8]<\/a> <a href=\"https:\/\/www.fiercetelecom.com\/telecom\/at-t-pleads-fcc-to-streamline-legacy-data-voice-retirement-processes\" target=\"_blank\" rel=\"noopener\">https:\/\/www.fiercetelecom.com\/telecom\/at-t-pleads-fcc-to-streamline-legacy-data-voice-retirement-processes<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama. Si en un principio fue la neutralidad de la red su objetivo, enterrando el concepto[1], ahora toca el turno del apagado de la red legada de cobre. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":96207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,12],"tags":[],"class_list":["post-96194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-opinion","category-regulacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EEUU quiere cambiar cobre por accesos inal\u00e1mbricos - UGT Comunicaciones<\/title>\n<meta name=\"description\" content=\"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos\" \/>\n<meta property=\"og:description\" content=\"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/\" \/>\n<meta property=\"og:site_name\" content=\"UGT Comunicaciones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ugt.comunicaciones\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-05T06:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"278\" \/>\n\t<meta property=\"og:image:height\" content=\"184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"UGT\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:site\" content=\"@ugtcom\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"UGT\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/\"},\"author\":{\"name\":\"UGT\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\"},\"headline\":\"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos\",\"datePublished\":\"2018-02-05T06:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/\"},\"wordCount\":651,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/EEUU_cobre_.jpg\",\"articleSection\":[\"Opini\u00f3n\",\"Regulaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/\",\"name\":\"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos - UGT Comunicaciones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/EEUU_cobre_.jpg\",\"datePublished\":\"2018-02-05T06:00:50+00:00\",\"description\":\"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/EEUU_cobre_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/EEUU_cobre_.jpg\",\"width\":278,\"height\":184,\"caption\":\"EEUU_cobre_\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"name\":\"UGT Comunicaciones\",\"description\":\"Sindicato de Telecomunicaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#organization\",\"name\":\"UGT Comunicaciones\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"contentUrl\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/comunicaciones_logo.png\",\"width\":298,\"height\":81,\"caption\":\"UGT Comunicaciones\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ugt.comunicaciones\\\/\",\"https:\\\/\\\/x.com\\\/ugtcom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ugtcomunicaciones.es\\\/wordpress\\\/#\\\/schema\\\/person\\\/eba0fc3fe5b444531d94d4368cba89ed\",\"name\":\"UGT\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g\",\"caption\":\"UGT\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos - UGT Comunicaciones","description":"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/","og_locale":"es_ES","og_type":"article","og_title":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos","og_description":"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...","og_url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/","og_site_name":"UGT Comunicaciones","article_publisher":"https:\/\/www.facebook.com\/ugt.comunicaciones\/","article_published_time":"2018-02-05T06:00:50+00:00","og_image":[{"width":278,"height":184,"url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg","type":"image\/jpeg"}],"author":"UGT","twitter_card":"summary_large_image","twitter_creator":"@ugtcom","twitter_site":"@ugtcom","twitter_misc":{"Escrito por":"UGT","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#article","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/"},"author":{"name":"UGT","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed"},"headline":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos","datePublished":"2018-02-05T06:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/"},"wordCount":651,"publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg","articleSection":["Opini\u00f3n","Regulaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/","name":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos - UGT Comunicaciones","isPartOf":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#primaryimage"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg","datePublished":"2018-02-05T06:00:50+00:00","description":"La nueva composici\u00f3n del regulador de las telecos estadounidense, la FCC, ahora controlada por los republicanos de Trump, sigue dando pasos hacia el desmantelamiento del legado de Obama...","breadcrumb":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#primaryimage","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2018\/01\/EEUU_cobre_.jpg","width":278,"height":184,"caption":"EEUU_cobre_"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/eeuu-quiere-cambiar-cobre-accesos-inalambricos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/"},{"@type":"ListItem","position":2,"name":"EEUU quiere cambiar cobre por accesos inal\u00e1mbricos"}]},{"@type":"WebSite","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#website","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","name":"UGT Comunicaciones","description":"Sindicato de Telecomunicaciones","publisher":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#organization","name":"UGT Comunicaciones","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","contentUrl":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-content\/uploads\/2024\/04\/comunicaciones_logo.png","width":298,"height":81,"caption":"UGT Comunicaciones"},"image":{"@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ugt.comunicaciones\/","https:\/\/x.com\/ugtcom"]},{"@type":"Person","@id":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/#\/schema\/person\/eba0fc3fe5b444531d94d4368cba89ed","name":"UGT","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2a16057d620a4c646bcfc171c4f23030879ebbdd346f0525bd5d4a564e57e13d?s=96&d=mm&r=g","caption":"UGT"}}]}},"_links":{"self":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/96194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/comments?post=96194"}],"version-history":[{"count":0,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/posts\/96194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media\/96207"}],"wp:attachment":[{"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/media?parent=96194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/categories?post=96194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ugtcomunicaciones.es\/wordpress\/wp-json\/wp\/v2\/tags?post=96194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}